{"id":10156,"date":"2026-02-03T23:00:13","date_gmt":"2026-02-03T22:00:13","guid":{"rendered":"https:\/\/esportsmunicipalsalzira.com\/aquests-son-els-resultats-dels-nostres-minis-estos-son-los-resultados-de-nuestros-minis-nbalzira-familiablau\/"},"modified":"2026-02-03T23:00:13","modified_gmt":"2026-02-03T22:00:13","slug":"aquests-son-els-resultats-dels-nostres-minis-estos-son-los-resultados-de-nuestros-minis-nbalzira-familiablau","status":"publish","type":"post","link":"https:\/\/esportsmunicipalsalzira.com\/es\/aquests-son-els-resultats-dels-nostres-minis-estos-son-los-resultados-de-nuestros-minis-nbalzira-familiablau\/","title":{"rendered":"\u00a1Estos son los resultados de nuestros minis! \u2022 \u00a1Estos son los resultados de nuestros minis! #NBAlzira #familiaazul"},"content":{"rendered":"<p><br \/>\n\u00a1Estos son los resultados de nuestros minis! \u2728\ud83c\udfc0<\/p>\n<p>\u2022<\/p>\n<p>\u00a1Estos son los resultados de nuestros minis! \u2728\ud83c\udfc0<\/p>\n<p>#NBAlzira #familiaazulgrana #valencia #alzira #basketball<\/p>\n<p><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/02\/626045551_18444001615110518_1597962907729164435_n.webp.jpeg\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/02\/626045551_18444001615110518_1597962907729164435_n.webp.jpeg\" \/><\/a><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/www.facebook.com\/100063537194811\/posts\/1521824529945439\">source<\/a>  <\/p>","protected":false},"excerpt":{"rendered":"<p>Aquests s\u00f3n els resultats dels nostres minis! \u2728\ud83c\udfc0 \u2022 \u00a1Estos son los resultados de nuestros minis! \u2728\ud83c\udfc0 #NBAlzira #familiablaugrana #valencia #alzira #basketball Source<\/p>","protected":false},"author":2,"featured_media":10157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esports-alzira"],"featured_image_src":{"landsacpe":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/02\/626045551_18444001615110518_1597962907729164435_n.webp-1080x445.jpeg",1080,445,true],"list":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/02\/626045551_18444001615110518_1597962907729164435_n.webp-463x348.jpeg",463,348,true],"medium":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/02\/626045551_18444001615110518_1597962907729164435_n.webp-240x300.jpeg",240,300,true],"full":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/02\/626045551_18444001615110518_1597962907729164435_n.webp.jpeg",1080,1350,false]},"_links":{"self":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/10156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/comments?post=10156"}],"version-history":[{"count":0,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/10156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media\/10157"}],"wp:attachment":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media?parent=10156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/categories?post=10156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/tags?post=10156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}