{"id":10781,"date":"2026-09-01T11:06:56","date_gmt":"2026-09-01T09:06:56","guid":{"rendered":"https:\/\/esportsmunicipalsalzira.com\/alex-ramiro-acaba-sise-en-leuropeu-sub-15-dhalterofilia-de-pristina-elseisdoble-com\/"},"modified":"2026-09-01T11:06:56","modified_gmt":"2026-09-01T09:06:56","slug":"alex-ramiro-acaba-sise-en-leuropeu-sub-15-dhalterofilia-de-pristina-elseisdoble-com","status":"publish","type":"post","link":"https:\/\/esportsmunicipalsalzira.com\/es\/alex-ramiro-acaba-sise-en-leuropeu-sub-15-dhalterofilia-de-pristina-elseisdoble-com\/","title":{"rendered":"\u00c1lex Ramiro termina sexto en el Europeo sub-15 de halterofilia de Pristina \u2013 elseisdoble.com"},"content":{"rendered":"<p><br \/>\n\u00c1lex Ramiro termina sexto en el Europeo sub-15 de halterofilia de Pristina \u2013 elseisdoble.com<\/p>\n<p><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/09\/10897793614473947148.jpeg\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/09\/10897793614473947148.jpeg\" \/><\/a><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/www.facebook.com\/100063537194811\/posts\/1722660173195206\">source<\/a>  <\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c1lex Ramiro acaba sis\u00e9 en l\u2019Europeu sub-15 d\u2019halterof\u00edlia de Pristina &#8211; elseisdoble.com Source<\/p>","protected":false},"author":2,"featured_media":10782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esports-alzira"],"featured_image_src":{"landsacpe":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/09\/10897793614473947148.jpeg",800,417,false],"list":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/09\/10897793614473947148-463x348.jpeg",463,348,true],"medium":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/09\/10897793614473947148-300x156.jpeg",300,156,true],"full":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2026\/09\/10897793614473947148.jpeg",800,417,false]},"_links":{"self":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/10781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/comments?post=10781"}],"version-history":[{"count":0,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/10781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media\/10782"}],"wp:attachment":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media?parent=10781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/categories?post=10781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/tags?post=10781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}