{"id":5306,"date":"2023-05-03T21:25:14","date_gmt":"2023-05-03T19:25:14","guid":{"rendered":"https:\/\/esportsmunicipalsalzira.com\/hi-ha-coses-que-el-desti-marca-i-que-2-de-novembre-el-del-nostre-centenari-al-suner-jugarem-la-copa-rfef-fou-una-dei\/"},"modified":"2023-05-03T21:25:14","modified_gmt":"2023-05-03T19:25:14","slug":"hi-ha-coses-que-el-desti-marca-i-que-2-de-novembre-el-del-nostre-centenari-al-suner-jugarem-la-copa-rfef-fou-una-dei","status":"publish","type":"post","link":"https:\/\/esportsmunicipalsalzira.com\/es\/hi-ha-coses-que-el-desti-marca-i-que-2-de-novembre-el-del-nostre-centenari-al-suner-jugarem-la-copa-rfef-fou-una-dei\/","title":{"rendered":"Hay cosas que el destino marca, y que 2 de noviembre, el de nuestro Centenario en el Su\u00f1er jugaremos la Copa RFEF fue una de ellas"},"content":{"rendered":"<p><br \/>\n<img decoding=\"async\"  title=\"\" src=\"https:\/\/scontent-mad1-1.xx.fbcdn.net\/v\/t15.5256-10\/343269073_942602666778514_5741378783197489966_n.jpg?stp=dst-jpg_p180x540&#038;_nc_cat=103&#038;ccb=1-7&#038;_nc_sid=ad6a45&#038;_nc_ohc=JnXcZ-YCZuMAX_Va4KZ&#038;_nc_ht=scontent-mad1-1.xx&#038;oh=00_AfCdA3MbynTF7fT2O7TkKMnNOpjshGg4Mk69vz4TzCHKig&#038;oe=6459FA74\" \/><\/a><br \/>\ud83d\udcf9 Hi ha coses que el dest\u00ed marca, i que 2 de novembre, el del nostre Centenari al Su\u00f1er jugarem la Copa RFEF fou una d&#8217;eixes coses meravelloses.<\/p>\n<p>\u2764\ufe0f \u00c9rem feli\u00e7os i la vostra for\u00e7a fou incre\u00efble.<\/p>\n<p>\ud83c\udfb6 Al ritme de La F\u00famiga i amb aquest v\u00eddeo patrocinat per Comunikar i realitzat per Toni Mazo vos diem: \ud835\udc86\ud835\udc95 \ud835\udc8f\ud835\udc86\ud835\udc84\ud835\udc86\ud835\udc94\ud835\udc94\ud835\udc8a\ud835\udc95\ud835\udc86\ud835\udc8e.<\/p>\n<p>\ud83d\udcb3 Diumenge a les 12 h rebem al Ibiza Islas Pitiusas en casa per un duel clau i amb uns preus especials volem un Su\u00f1er intens. Compra-les JA en alzira.deporges.com o en el Su\u00f1er el mateix dia del partit.<\/p>\n<p>I \u00e9s que&#8230; \ud835\udc84\ud835\udc90\ud835\udc8e \ud835\udc8f\ud835\udc90 \ud835\udc95\ud835\udc86 \ud835\udc97\ud835\udc82\ud835\udc8a\ud835\udc88 \ud835\udc82 \ud835\udc86\ud835\udc94\ud835\udc95\ud835\udc8a\ud835\udc8e\ud835\udc82\ud835\udc93&#8230;<br \/><div id=\"fb-root\"><\/div><script>window.fbAsyncInit = function() {FB.init({appId      : '',xfbml      : true,version    : 'v2.5'});var my_video_player;FB.Event.subscribe('xfbml.ready', function(msg) {if (msg.type === 'video') {my_video_player = msg.instance; my_video_player.unmute();}});};(function(d, s, id) {  var js, fjs = d.getElementsByTagName(s)[0];  if (d.getElementById(id)) return;  js = d.createElement(s); js.id = id;  js.src = \"\/\/connect.facebook.net\/en_US\/sdk.js#xfbml=1&version=v2.3\";  fjs.parentNode.insertBefore(js, fjs);}(document, 'script', 'facebook-jssdk'));  <\/script><div class=\"fb-video\"    data-autoplay=\"false\" data-width=\"500\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/video.php?v=241805181857006&set=vb.500808182&type=1\"><div class=\"fb-xfbml-parse-ignore\"><\/div><\/div>\n\n\n\t\n\n<br \/>\n<br \/>\n<br \/><a href=\"https:\/\/www.facebook.com\/100063537194811\/posts\/719771493484084\">Source<\/a>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcf9 Hi ha coses que el dest\u00ed marca, i que 2 de novembre, el del nostre Centenari al Su\u00f1er jugarem la Copa RFEF fou una d&#8217;eixes coses meravelloses. \u2764\ufe0f \u00c9rem feli\u00e7os i la vostra for\u00e7a fou incre\u00efble. \ud83c\udfb6 Al ritme de La F\u00famiga i amb aquest v\u00eddeo patrocinat per Comunikar i realitzat per Toni Mazo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esports-alzira"],"featured_image_src":{"landsacpe":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2023\/05\/343269073_942602666778514_5741378783197489966_n-960x445.jpg",960,445,true],"list":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2023\/05\/343269073_942602666778514_5741378783197489966_n-463x348.jpg",463,348,true],"medium":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2023\/05\/343269073_942602666778514_5741378783197489966_n-300x169.jpg",300,169,true],"full":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2023\/05\/343269073_942602666778514_5741378783197489966_n.jpg",960,540,false]},"_links":{"self":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/5306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/comments?post=5306"}],"version-history":[{"count":0,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/5306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media\/5307"}],"wp:attachment":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media?parent=5306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/categories?post=5306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/tags?post=5306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}