{"id":9367,"date":"2025-07-21T17:04:34","date_gmt":"2025-07-21T15:04:34","guid":{"rendered":"https:\/\/esportsmunicipalsalzira.com\/divendres-passat-tinguerem-de-nou-representacio-en-la-volta-a-peu-del-poble-amic-de-polinya-del-xuquer-incansables-els\/"},"modified":"2025-07-21T17:04:34","modified_gmt":"2025-07-21T15:04:34","slug":"divendres-passat-tinguerem-de-nou-representacio-en-la-volta-a-peu-del-poble-amic-de-polinya-del-xuquer-incansables-els","status":"publish","type":"post","link":"https:\/\/esportsmunicipalsalzira.com\/es\/divendres-passat-tinguerem-de-nou-representacio-en-la-volta-a-peu-del-poble-amic-de-polinya-del-xuquer-incansables-els\/","title":{"rendered":"El pasado viernes tendremos de nuevo representaci\u00f3n en la vuelta a pie del pueblo amigo de Poliny\u00e0 del Xuquer, incansables los"},"content":{"rendered":"<p><br \/>\nEl pasado viernes tendremos de nuevo representaci\u00f3n en la vuelta a pie del pueblo amigo de Poliny\u00e0 del Xuquer, incansables nuestros corredores!!!\u270c\ufe0f\ud83d\udc4f\ud83d\udc4f\ud83d\udc4f<\/p>\n<p>En esta ocasi\u00f3n los m\u00e9ritos que logramos quedaron de la siguiente forma:<\/p>\n<p>\ud83d\udd1d 2\u00ba CLASIFICADO VETERANO C<br \/>\n       \ud83e\udd48 DAVID NAVIDAD GARC\u00cdA<\/p>\n<p>\ud83d\udd1d 2\u00ba CLASIFICADO VETERANO B<br \/>\n       \ud83e\udd48 JUAN MANUEL CLIMENT PUERTOS<\/p>\n<p>\ud83d\udd1d 3er CLASIFICADO VETERANO EN<br \/>\n       \ud83e\udd49 RAFA BALAGUER LOBO<\/p>\n<p>\ud83d\udd1d 3era CLASIFICADA VETERANA A<br \/>\n       \ud83e\udd49 YOLANDA GALLEGO BALLESTER<\/p>\n<p>\u00a1Qu\u00e9 mayores sois todos, agradecer como siempre la participaci\u00f3n de todos!!! Da gusto contar siempre con gente que nos representa por todas partes!! \ud83d\udc9c\ud83d\udda4\ud83e\udd0d ENHORABUENA!!!<\/p>\n<p>SOMOS AMIGOS, SOMOS DEPORTE, SOMOS CLUB DE ATLETISMO RICKYSPORTEAM ALZIRA!!!<\/p>\n<p> \u2026.Ven y har\u00e1s amigos\u2026.\ud83e\udec2\ud83e\udd1d<\/p>\n<p><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/521405532_18045782357555701_6104083931640218929_n.webp\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/521405532_18045782357555701_6104083931640218929_n.webp\" \/><\/a><br \/><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/520432345_18045782369555701_4434304125817510162_n.webp\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/520432345_18045782369555701_4434304125817510162_n.webp\" \/><\/a><br \/><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/519427912_18045782378555701_4321372503611807079_n.webp\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/519427912_18045782378555701_4321372503611807079_n.webp\" \/><\/a><br \/><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/520466544_18045782402555701_6046775681421922973_n.webp\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/520466544_18045782402555701_6046775681421922973_n.webp\" \/><\/a><br \/><a href=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/522695845_18045782432555701_6814344941446204014_n.webp\"><img decoding=\"async\" class=\"wp_automatic_fb_img\" title=\"\" src=\"https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/522695845_18045782432555701_6814344941446204014_n.webp\" \/><\/a><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/www.facebook.com\/100063537194811\/posts\/1340497434744817\">source<\/a>  <\/p>","protected":false},"excerpt":{"rendered":"<p>Divendres passat tinguerem de nou representaci\u00f3 en la volta a peu del poble amic de Poliny\u00e0 del Xuquer, incansables els nostres corredors!!!\u270c\ufe0f\ud83d\udc4f\ud83d\udc4f\ud83d\udc4f En aquesta ocassi\u00f3 els m\u00e8rits que vam aconseguir van quedar de la seg\u00fcent manera: \ud83d\udd1d 2on CLASSIFICAT VETER\u00c0 C \ud83e\udd48 DAVID NADAL GARC\u00cdA \ud83d\udd1d 2on CLASSIFICAT VETER\u00c0 B \ud83e\udd48 JUAN MANUEL CLIMENT PUERTOS [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esports-alzira"],"featured_image_src":{"landsacpe":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/521405532_18045782357555701_6104083931640218929_n.webp-1140x445.jpeg",1140,445,true],"list":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/521405532_18045782357555701_6104083931640218929_n.webp-463x348.jpeg",463,348,true],"medium":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/521405532_18045782357555701_6104083931640218929_n.webp-300x300.jpeg",300,300,true],"full":["https:\/\/esportsmunicipalsalzira.com\/wp-content\/uploads\/2025\/07\/521405532_18045782357555701_6104083931640218929_n.webp.jpeg",1440,1440,false]},"_links":{"self":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/9367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/comments?post=9367"}],"version-history":[{"count":0,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/posts\/9367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media\/9368"}],"wp:attachment":[{"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/media?parent=9367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/categories?post=9367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportsmunicipalsalzira.com\/es\/wp-json\/wp\/v2\/tags?post=9367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}